{"id":3067,"date":"2021-04-12T17:58:36","date_gmt":"2021-04-12T23:58:36","guid":{"rendered":"https:\/\/centroamerica.wordcamp.org\/2021\/?p=3067"},"modified":"2021-04-12T17:58:36","modified_gmt":"2021-04-12T23:58:36","slug":"patrocinador-izalco-easywp","status":"publish","type":"post","link":"https:\/\/centroamerica.wordcamp.org\/2021\/patrocinador-izalco-easywp\/","title":{"rendered":"Patrocinador Izalco &#8211; EasyWP"},"content":{"rendered":"\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">El WordCamp Centroam\u00e9rica 2021 agradece a <strong><a href=\"https:\/\/www.easywp.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">EasyWP<\/a><\/strong>, por ser uno de sus patrocinadores del grupo Izalco y por su confianza en la realizaci\u00f3n de este evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, te presentamos informaci\u00f3n relevante sobre este patrocinador como sus servicios y valor agregado, entre otros datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre EasyWP\u2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.easywp.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">EasyWP<\/a> es una soluci\u00f3n para alojamiento de WordPress administrado, es el m\u00e1s r\u00e1pido y mas asequible en cuanto a precios en el mercado, ya que la empresa busca que Internet sea accesible para todos, por este motivo eliminaron los intermediarios, para ofrecer a sus clientes valor, rendimiento y confiabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EasyWP se encarga de hacer el trabajo duro, para que el cliente no deba preocuparse por manejar interfaces de panel o averiguar c\u00f3mo instalar WordPress. Este servicio ofrece la \u00faltima tecnolog\u00eda en la nube, para que sus clientes tengan una experiencia de configuraci\u00f3n sencilla y completamente optimizada para WordPress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plataforma de EasyWP est\u00e1 dise\u00f1ada exclusivamente para alojar sitios web de WordPress. Est\u00e1 construido sobre plataforma basada en la nube, por lo que cualquier falla en el servidor, no afectar\u00e1 a los sitios web de los clientes y los recursos no se comparten con otros clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas las configuraciones del lado del servidor son administradas por Namecheap, por lo que no se requerir\u00e1 elegir una versi\u00f3n de PHP, configurar l\u00edmites o cargar archivos manualmente.<\/p>\n\n\n\n<h4 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\"><strong>Beneficios de EasyWP<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Con el alojamiento en EasyWP, los clientes podr\u00e1n:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Iniciar una tienda en l\u00ednea utilizando el complemento WooCommerce<\/li><li>Personalizar su sitio web sin c\u00f3digo, utilizando Jetpack<\/li><li>Optmizar su sitio web con Yoast<\/li><li>Hacer copias de seguridad desde una interfaz sencilla y f\u00e1cil de usar<\/li><li>Obtener acceso a los archivos con SFTP que permite a los clientes un control total sobre los archivos de su sitio web<\/li><li>Poner el sitio en modo de mantenimiento hasta que est\u00e9 listo<\/li><li>Obtener de forma gratuita el cifrado, validaci\u00f3n y confiabilidad del sitio con Positive SSL<\/li><li>Servicio de soporte 24 horas al d\u00eda, los 7 d\u00edas de la semana<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">No existe una receta para elegir el mejor alojamiento para un sitio web, depende de las necesidades de cada cliente y de que este se sienta c\u00f3modo con el manejo de su sitio web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para aquellos que est\u00e1n comenzando o que prefieren una interfaz f\u00e1cil de usar, EasyWp es una excelente opci\u00f3n.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El WordCamp Centroam\u00e9rica 2021 agradece a EasyWP, por ser uno de sus patrocinadores del grupo Izalco y por su confianza en la realizaci\u00f3n de este evento. <\/p>\n","protected":false},"author":18567186,"featured_media":3070,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[],"class_list":["post-3067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","entry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheCLM-Nt","jetpack_featured_media_url":"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/04\/WPEASY_AGRADECIMIENTO2.png","_links":{"self":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/3067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/users\/18567186"}],"replies":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/comments?post=3067"}],"version-history":[{"count":1,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/3067\/revisions"}],"predecessor-version":[{"id":3071,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/3067\/revisions\/3071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media\/3070"}],"wp:attachment":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media?parent=3067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/categories?post=3067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/tags?post=3067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}