{"id":980,"date":"2021-02-17T16:53:06","date_gmt":"2021-02-17T22:53:06","guid":{"rendered":"https:\/\/centroamerica.wordcamp.org\/2021\/?p=980"},"modified":"2021-02-23T10:07:20","modified_gmt":"2021-02-23T16:07:20","slug":"presentando-la-identidad-del-wordcamp-centroamerica","status":"publish","type":"post","link":"https:\/\/centroamerica.wordcamp.org\/2021\/presentando-la-identidad-del-wordcamp-centroamerica\/","title":{"rendered":"Presentando la identidad del WordCamp Centroam\u00e9rica"},"content":{"rendered":"\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Introducci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solicitud:<\/strong> <em>Las propuestas de logo deber\u00e1n representar la identidad de la regi\u00f3n y la comunidad. El logo del WCCA 2020 est\u00e1 compuesto por dos partes; la marca y el isotipo. La marca ser\u00e1 la parte constante de la identidad visual del WCCA. Tiene que ser reutilizable, o en otra palabras, se va a utilizar el logo en futuras ediciones del WCCA, por lo que no debe ser asociado \u00fanicamente con la primera edici\u00f3n del evento.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objetivo:<\/strong> <em>Desarrollar la marca de un evento regional que represente la identidad de todos los pa\u00edses de Centroam\u00e9rica que son parte de la comunidad WordPress.<\/em><\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Dise\u00f1o del logo WCCA: <\/h2>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Proceso creativo<\/h3>\n\n\n\n<p class=\"has-text-align-center has-text-align-justify wp-block-paragraph\">El equipo de dise\u00f1o del logo de WordCamp Centroam\u00e9rica, consta de dos miembros: <a href=\"https:\/\/www.linkedin.com\/in\/carlos-l%C3%B3pez-778a81aa\">Carlos L\u00f3pez<\/a>, el l\u00edder del equipo, quien se dedica a ser un dise\u00f1ador Digital con experiencia en UX\/UI, con 5 a\u00f1os de trayectoria creando experiencias de marcas, tanto en medios tradicionales como digitales. Por \u00faltimo, pero no menos importante, <a href=\"https:\/\/www.linkedin.com\/in\/bayardomartinez\/\">Bayardo Mart\u00ednez<\/a>, Dise\u00f1ador Estrat\u00e9gico, con 12+ a\u00f1os de experiencia en desarrollo integral de marcas, direcci\u00f3n de arte, redacci\u00f3n creativa y tomar caf\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misi\u00f3n principal del equipo fue dise\u00f1ar un logotipo en el que pudieran representar la identidad de toda la regi\u00f3n y la comunidad; con elementos visuales, tipograf\u00eda y colores, que permitan personalizar f\u00e1cilmente para reflejar la ciudad anfitriona de las futuras ediciones de WordCamp Centroam\u00e9rica.<\/p>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Inspiraci\u00f3n inicial<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La regi\u00f3n centroamericana es rica en flora, fauna y culturas ancestrales. Estos elementos se repiten de manera constante en los siete pa\u00edses que la conforman: Belice, Guatemala, El Salvador, Honduras, Nicaragua, Costa Rica y Panam\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es por ello que se tom\u00f3 la decisi\u00f3n de recopilar elementos gr\u00e1ficos de estos rasgos caracter\u00edsticos en com\u00fan, para que se pudieran utilizar en el logo del primer WordCamp Centroam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los elementos visuales que se utilizaron para formar el logotipo, fueron las siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aves \u2013 Ind\u00edgenas \u2013 Flora<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/azulejos-1024x555-1.png\" alt=\"Flora y Fauna Centroamericana\" class=\"wp-image-981\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/azulejos-1024x555-1.png 1024w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/azulejos-1024x555-1-300x163.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/azulejos-1024x555-1-768x416.png 768w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/azulejos-1024x555-1-500x271.png 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las aves que inspiraron para la creaci\u00f3n del logo fueron las aves nacionales por cada pa\u00eds centroamericano son: Tuc\u00e1n de Belice; el Quetzal de Guatemala; Torogoz de El Salvador; Ara Macao de Honduras; Guardabarranco de Nicaragua; Yig\u00fcirro de Costa Rica y \u00c1guila Harp\u00eda de Panam\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cultura de los grupos \u00e9tnicos de Centroam\u00e9rica se encuentra altamente influenciada por los Mayas, lo que fue un punto relevante para el logo de WordCamp Centroam\u00e9rica. Cabe destacar, que cada pa\u00eds cont\u00f3 con la presencia de grupos espec\u00edficos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Belice, fueron los gar\u00edfunas; en Costa Rica los Malekus; en El Salvador los Nahuat-Pipil; en Guatemala, los Mayas; en Honduras los Lencas; en Nicaragua los Niquiranos y en Panam\u00e1 los Ember\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros elementos inspirativos fue la flora de la regi\u00f3n. En la que se tom\u00f3 de referencia, cada una de las flores nacionales, que mencionamos a continuaci\u00f3n: Orquidea negra de Belice; Monja Blanca de Guatemala; Izote de El Salvador; Orqu\u00eddea de Honduras; Sacuanjoche de Nicaragua; Guaria Morada de Costa Rica y Flor del esp\u00edritu Santo de Panam\u00e1.<\/p>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Unificaci\u00f3n de los elementos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se unificaron estos rasgos, uno de los mayores retos fue encontrar una soluci\u00f3n que podr\u00eda llegar a cabo la presentaci\u00f3n de la UNI\u00d3N de nuestros pa\u00edses. Todo esto de una forma rica en esencia, para llegar a una base simple de curvas, que al final nos dar\u00eda la pauta para poder seguir dentro del proceso creativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El uso del m\u00e9todo creativo emp\u00edrico tambi\u00e9n nos ayud\u00f3 a crear ciertas v\u00edas, para poder entender que \u00e9ramos anteriormente la Rep\u00fablica Federal de Centro Am\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de los valores m\u00e1s importantes para la formaci\u00f3n del logo, fue la ideolog\u00eda de ser pa\u00edses con un toque m\u00e1gico y colorido. Estos patrones que van desde Belice hasta Panam\u00e1, particularmente en nuestras ra\u00edces, que muestran de d\u00f3nde somos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"272\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/logo-inical.png\" alt=\"Primer borrador del logo inicial\" class=\"wp-image-982\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/logo-inical.png 512w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/logo-inical-300x159.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/logo-inical-500x266.png 500w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Primer borrador del logo inicial<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Nuestra identidad fundamental<\/h3>\n\n\n\n<h4 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Creando experiencia y significado<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">ntentamos utilizar como base nuestra flora nacional, nuestras hermosas aves que viven dentro de la regi\u00f3n centroamericana, como nuestros antepasados que han dejado un legado grande a trav\u00e9s de la historia. Hemos desarrollado propuestas que podr\u00edan llevarnos al camino correcto, pero sent\u00edamos que parte de la propuesta faltaba algo fundamental:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"659\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/inciales2.png\" alt=\"Segundo borrador de propuestas de logo\" class=\"wp-image-983\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/inciales2.png 1024w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/inciales2-300x193.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/inciales2-768x494.png 768w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/inciales2-466x300.png 466w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Segundo borrador de propuestas de logo<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como punto de partida nos encontramos con algo interesante, que pod\u00eda explotar a base de un centro que contuviera las caracter\u00edsticas antes mencionadas AVES-IND\u00cdGENAS-FLORA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unificadas dentro de una regi\u00f3n espec\u00edfica, para poder representar a nuestra Centroam\u00e9rica basada en la amabilidad natural y mosaico \u00e9tnico. Siendo as\u00ed el origen de nuestra propuesta de WordCamp Centroam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parte de la creaci\u00f3n cont\u00f3 con el apoyo de organizadores y expertos del tema, quienes sugirieron representar la riqueza del \u00e1rea. Por ende, cada p\u00e9talo representa un pa\u00eds y un valor agregado. El logotipo en su forma es una uni\u00f3n y cada pa\u00eds est\u00e1 conectado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo siempre el p\u00e9talo del centro el emblem\u00e1tico, \u00e9l cual deber\u00e1 lucirse por cada pa\u00eds cuando sea sede principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de nuestra identidad visual nos sentimos felices de querer expresarnos de una manera sutil como: Somos nuestras ra\u00edces y de d\u00f3nde venimos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"345\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/sktch.png\" alt=\"Representaci\u00f3n de pa\u00edses centroamericanos en los elementos de logo\" class=\"wp-image-984\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/sktch.png 1024w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/sktch-300x101.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/sktch-768x259.png 768w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/sktch-500x168.png 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">La forma final<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es con gran agrado que introducimos la version final de la identidad visual de WordCamp Centroam\u00e9rica:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"386\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-1024x386.png\" alt=\"Logo Final WordCamp Centroam\u00e9rica 2021\" class=\"wp-image-985\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-1024x386.png 1024w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-300x113.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-768x290.png 768w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-500x189.png 500w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-1536x579.png 1536w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-2048x773.png 2048w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-1568x592.png 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Del mismo modo cada marca seg\u00fan formatos puede tener sus variaciones. Hemos decidido tener opciones de ubicaci\u00f3n siempre manteniendo el centro como ubicaci\u00f3n distinguida. Adjuntamos nuestras versiones para diferentes medios que se necesiten:<\/p>\n\n\n\n<div class=\"wp-block-columns has-white-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"386\" src=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-1024x386.png\" alt=\"Variaciones del logo WCCA 2021\" class=\"wp-image-986\" srcset=\"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-1024x386.png 1024w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-300x113.png 300w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-768x290.png 768w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-500x189.png 500w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-1536x579.png 1536w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-2048x773.png 2048w, https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/LOGO-WCCAai_Mesa-de-trabajo-1-copia-1-1568x592.png 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">La vida, nuestro ser y los colores<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Parte del proceso para nuestra marca Wordcamp Centroam\u00e9rica. presentamos un poco de nuestros elementos visuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada uno de los colores seleccionados para los p\u00e9talos del logo de WordCamp Centroam\u00e9rica, tiene una relaci\u00f3n directa con cada pa\u00eds de la regi\u00f3n. Para que, como se ha mencionado previamente, destaqu\u00e9 en el centro el color del pa\u00eds sede para futuras organizaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El amarillo representa la vibrante Guatemala, fue seleccionado por ser un color fuerte y caracter\u00edstico de la Ciudad de Antigua Guatemala. Asimismo, por la felicidad, alegr\u00eda y generosidad de su gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rojo fue dado a la ex\u00f3tica Costa Rica, por dos motivos principales. Uno de ellos, por ser un color distintivo en el traje folkl\u00f3rico y la bandera. Segundo por la lucha de la libertad y amor a la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El turquesa fue asignado a Belice, por sus majestuosas aguas turquesas. Y representan lo natural, relajante y envolvente de sus paisajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El azul oscuro fue otorgado a Nicaragua, por ser un pa\u00eds en el que predominan lagos y mares. De igual manera, refleja la libertad y lealtad del pueblo nicarag\u00fcense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rosado representa un s\u00edmbolo principal de El Salvador. De la misma manera se caracteriza por ser uno de los colores que representan la fineza del Maquilishuat, su \u00e1rbol nacional. Destacando amabilidad, entrega y generosidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El azul claro para nuestro Panam\u00e1. Por ser uno de los pa\u00edses que cada a dia se esfuerzan por ser emprendedores. Su Canal maravilloso que conecta con los dos oc\u00e9anos principales: el Oc\u00e9ano Atl\u00e1ntico y el Pac\u00edfico, esa uni\u00f3n que representa la serenidad y responsabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Honduras por supuesto representando ese color naranja que nos recuerda a todos los habitantes por nuestra sencillez, calidez y vivacidad que nos lleva a ser fuertes cada d\u00eda.<\/p>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#79ebe2\">Felices en comenzar nuestra era<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos muy felices haber explorado caracter\u00edsticas que nos hac\u00edan sentirnos como \u00fanicos. Trabajamos base a nuestra experiencia de vida, nos hemos dado cuenta que nuestro valores principales son nuestras ra\u00edces. Nuestro comienzo y al pasar de los a\u00f1os, queremos que todo el mundo pueda reconocernos por lo que nos caracteriza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos historia y cultura. Para nosotros lanzar nuestra identidad nos ayuda en creer en nosotros mismos diciendo bienvenido WordCamp Centroam\u00e9rica para todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El WordCamp Centroam\u00e9rica se llevar\u00e1 a cabo los d\u00edas 15, 16 y 17 de abril del presente a\u00f1o en formato Online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pronto estaremos compartiendo m\u00e1s detalles del evento en nuestras redes sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentamos parte del proceso para crear nuestra marca WordCamp Centroam\u00e9rica. <\/p>\n","protected":false},"author":15079632,"featured_media":987,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[31,33,32],"class_list":["post-980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-wcca2021","tag-wordcampcentroamerica","tag-wordpress","entry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheCLM-fO","jetpack_featured_media_url":"https:\/\/centroamerica.wordcamp.org\/2021\/files\/2021\/02\/WEB.png","_links":{"self":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/users\/15079632"}],"replies":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/comments?post=980"}],"version-history":[{"count":4,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/980\/revisions"}],"predecessor-version":[{"id":1031,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/posts\/980\/revisions\/1031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media\/987"}],"wp:attachment":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media?parent=980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/categories?post=980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/tags?post=980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}