{"id":1918,"date":"2021-03-17T08:05:45","date_gmt":"2021-03-17T14:05:45","guid":{"rendered":"https:\/\/centroamerica.wordcamp.org\/2021\/?post_type=wcb_speaker&#038;p=1918"},"modified":"2021-03-17T08:05:45","modified_gmt":"2021-03-17T14:05:45","slug":"olga-molina-garcia","status":"publish","type":"wcb_speaker","link":"https:\/\/centroamerica.wordcamp.org\/2021\/speaker\/olga-molina-garcia\/","title":{"rendered":"Olga Molina Garcia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Soy una emprendedora reinventada. Despu\u00e9s de trabajar durante unos a\u00f1os en la construcci\u00f3n y tras la crisis del sector, di un giro a mi vida profesional y actualmente trabajo como dise\u00f1adora gr\u00e1fica y web freelance en mi propio proyecto olgamolinag.com. Tambi\u00e9n soy Mailchimp Partner. Utilizo WordPress como una de mis principales herramientas de trabajo desde que la descubr\u00ed. He formado parte del equipo de coorganizadores de la WordCamp Espa\u00f1a Online 2020 siendo responsable de su equipo de dise\u00f1o, soy coorganizadora de la WordCamp Valladolid y de la Meetup WordPress Valladolid. Muero de amor por los perros, no podr\u00eda vivir sin m\u00fasica, y cualquier m\u00ednimo detalle saca la mejor de mis sonrisas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soy una emprendedora reinventada. Despu\u00e9s de trabajar durante unos a\u00f1os en la construcci\u00f3n y tras la crisis del sector, di un giro a mi vida profesional y actualmente trabajo como dise\u00f1adora gr\u00e1fica y web freelance en mi propio proyecto olgamolinag.com. Tambi\u00e9n soy Mailchimp Partner. Utilizo WordPress como una de mis principales herramientas de trabajo desde&hellip; <a class=\"more-link\" href=\"https:\/\/centroamerica.wordcamp.org\/2021\/speaker\/olga-molina-garcia\/\">Seguir leyendo <span class=\"screen-reader-text\">Olga Molina Garcia<\/span><\/a><\/p>\n","protected":false},"author":10987929,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"olgamolinag","footnotes":""},"speaker_group":[],"class_list":["post-1918","wcb_speaker","type-wcb_speaker","status-publish","hentry","entry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheCLM-uW","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/21204dbf7894d6b3edc38f2a904ac76d904cbee798639f3955e879d6f77310eb?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/users\/10987929"}],"replies":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1918\/revisions"}],"predecessor-version":[{"id":1919,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1918\/revisions\/1919"}],"sessions":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/sessions\/1920?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speaker_group?post=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}