{"id":1997,"date":"2021-03-18T18:04:29","date_gmt":"2021-03-19T00:04:29","guid":{"rendered":"https:\/\/centroamerica.wordcamp.org\/2021\/?post_type=wcb_speaker&#038;p=1997"},"modified":"2021-03-18T18:04:29","modified_gmt":"2021-03-19T00:04:29","slug":"fernando-martinez-lira","status":"publish","type":"wcb_speaker","link":"https:\/\/centroamerica.wordcamp.org\/2021\/speaker\/fernando-martinez-lira\/","title":{"rendered":"Fernando Mart\u00ednez Lira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apasionado por el Marketing, la programaci\u00f3n y el aprendizaje continuo. Fernando es graduado en Administraci\u00f3n de Empresas &amp; Marketing, tiene un Posgrado en Gerencia y Liderazgo y cuenta con experiencia enfocada en el desarrollo de estrategias integrales de Marketing, consultor\u00edas de SEO y Marketing de Contenidos para Agencias de Marketing Digital, Universidad con presencia internacional, ONGs y en empresas B2B de tecnolog\u00eda en los Estados Unidos. Si no estoy hablando sobre Marketing y tecnolog\u00eda, estoy apoyando a mi equipo favorito de f\u00fatbol, jugando con mis mascotas o conociendo nuevos lugares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apasionado por el Marketing, la programaci\u00f3n y el aprendizaje continuo. Fernando es graduado en Administraci\u00f3n de Empresas &amp; Marketing, tiene un Posgrado en Gerencia y Liderazgo y cuenta con experiencia enfocada en el desarrollo de estrategias integrales de Marketing, consultor\u00edas de SEO y Marketing de Contenidos para Agencias de Marketing Digital, Universidad con presencia internacional,&hellip; <a class=\"more-link\" href=\"https:\/\/centroamerica.wordcamp.org\/2021\/speaker\/fernando-martinez-lira\/\">Seguir leyendo <span class=\"screen-reader-text\">Fernando Mart\u00ednez Lira<\/span><\/a><\/p>\n","protected":false},"author":14911570,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"ferlyra","footnotes":""},"speaker_group":[],"class_list":["post-1997","wcb_speaker","type-wcb_speaker","status-publish","hentry","entry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheCLM-wd","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/682b54e8d10c8d512301fbe1e8bfb040fc8116306c4d6ade3d1599a3d9320d4c?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/users\/14911570"}],"replies":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/comments?post=1997"}],"version-history":[{"count":1,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1997\/revisions"}],"predecessor-version":[{"id":1998,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speakers\/1997\/revisions\/1998"}],"sessions":[{"embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/sessions\/2017?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/media?parent=1997"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/centroamerica.wordcamp.org\/2021\/wp-json\/wp\/v2\/speaker_group?post=1997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}